{"id":25,"date":"2024-03-07T09:31:41","date_gmt":"2024-03-07T09:31:41","guid":{"rendered":"https:\/\/gras-arquitectos.com\/?page_id=25"},"modified":"2025-04-23T10:30:47","modified_gmt":"2025-04-23T10:30:47","slug":"politica-de-cookies","status":"publish","type":"page","link":"https:\/\/gras-arquitectos.com\/es\/politica-de-cookies\/","title":{"rendered":"Pol\u00edtica de Cookies"},"content":{"rendered":"\n<h1 class=\"wp-block-heading\">Pol\u00edtica de Cookies<\/h1>\n","protected":false},"excerpt":{"rendered":"<p>Pol\u00edtica de Cookies<\/p>\n","protected":false},"author":4,"featured_media":0,"parent":0,"menu_order":0,"comment_status":"closed","ping_status":"closed","template":"templates\/template-flexible.php","meta":{"_acf_changed":false,"inline_featured_image":false,"footnotes":""},"class_list":["post-25","page","type-page","status-publish","hentry"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.4 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Pol\u00edtica de Cookies - GRAS Reyn\u00e9s Arquitectos<\/title>\n<meta name=\"description\" content=\"Pol\u00edtica de cookies, las usamos para mejorar tu experiencia, personalizar contenido y ofrecer publicidad relevante\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/gras-arquitectos.com\/es\/politica-de-cookies\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Pol\u00edtica de Cookies - GRAS Reyn\u00e9s Arquitectos\" \/>\n<meta property=\"og:description\" content=\"Pol\u00edtica de cookies, las usamos para mejorar tu experiencia, personalizar contenido y ofrecer publicidad relevante\" \/>\n<meta property=\"og:url\" content=\"https:\/\/gras-arquitectos.com\/es\/politica-de-cookies\/\" \/>\n<meta property=\"og:site_name\" content=\"GRAS Reyn\u00e9s Arquitectos\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/GRASarquitectos\" \/>\n<meta property=\"article:modified_time\" content=\"2025-04-23T10:30:47+00:00\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Tiempo de lectura\" \/>\n\t<meta name=\"twitter:data1\" content=\"10 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/gras-arquitectos.com\\\/es\\\/politica-de-cookies\\\/\",\"url\":\"https:\\\/\\\/gras-arquitectos.com\\\/es\\\/politica-de-cookies\\\/\",\"name\":\"Pol\u00edtica de Cookies - GRAS Reyn\u00e9s Arquitectos\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/gras-arquitectos.com\\\/es\\\/#website\"},\"datePublished\":\"2024-03-07T09:31:41+00:00\",\"dateModified\":\"2025-04-23T10:30:47+00:00\",\"description\":\"Pol\u00edtica de cookies, las usamos para mejorar tu experiencia, personalizar contenido y ofrecer publicidad relevante\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/gras-arquitectos.com\\\/es\\\/politica-de-cookies\\\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/gras-arquitectos.com\\\/es\\\/politica-de-cookies\\\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/gras-arquitectos.com\\\/es\\\/politica-de-cookies\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/gras-arquitectos.com\\\/es\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Pol\u00edtica de Cookies\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/gras-arquitectos.com\\\/es\\\/#website\",\"url\":\"https:\\\/\\\/gras-arquitectos.com\\\/es\\\/\",\"name\":\"GRAS Reyn\u00e9s Architecture Studio\",\"description\":\"Estudio de arquitectura\",\"publisher\":{\"@id\":\"https:\\\/\\\/gras-arquitectos.com\\\/es\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/gras-arquitectos.com\\\/es\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/gras-arquitectos.com\\\/es\\\/#organization\",\"name\":\"GRAS Reyn\u00e9s Architecture Studio\",\"url\":\"https:\\\/\\\/gras-arquitectos.com\\\/es\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/gras-arquitectos.com\\\/es\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/gras-arquitectos.com\\\/wp-content\\\/uploads\\\/2024\\\/08\\\/0-logo-gras-arquitectos-vertical-google-1.jpg\",\"contentUrl\":\"https:\\\/\\\/gras-arquitectos.com\\\/wp-content\\\/uploads\\\/2024\\\/08\\\/0-logo-gras-arquitectos-vertical-google-1.jpg\",\"width\":720,\"height\":720,\"caption\":\"GRAS Reyn\u00e9s Architecture Studio\"},\"image\":{\"@id\":\"https:\\\/\\\/gras-arquitectos.com\\\/es\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/GRASarquitectos\",\"https:\\\/\\\/www.instagram.com\\\/grasreynesarquitectos\",\"https:\\\/\\\/www.linkedin.com\\\/company\\\/gras-reynes-arquitectos\\\/\"]}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Pol\u00edtica de Cookies - GRAS Reyn\u00e9s Arquitectos","description":"Pol\u00edtica de cookies, las usamos para mejorar tu experiencia, personalizar contenido y ofrecer publicidad relevante","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/gras-arquitectos.com\/es\/politica-de-cookies\/","og_locale":"es_ES","og_type":"article","og_title":"Pol\u00edtica de Cookies - GRAS Reyn\u00e9s Arquitectos","og_description":"Pol\u00edtica de cookies, las usamos para mejorar tu experiencia, personalizar contenido y ofrecer publicidad relevante","og_url":"https:\/\/gras-arquitectos.com\/es\/politica-de-cookies\/","og_site_name":"GRAS Reyn\u00e9s Arquitectos","article_publisher":"https:\/\/www.facebook.com\/GRASarquitectos","article_modified_time":"2025-04-23T10:30:47+00:00","twitter_card":"summary_large_image","twitter_misc":{"Tiempo de lectura":"10 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/gras-arquitectos.com\/es\/politica-de-cookies\/","url":"https:\/\/gras-arquitectos.com\/es\/politica-de-cookies\/","name":"Pol\u00edtica de Cookies - GRAS Reyn\u00e9s Arquitectos","isPartOf":{"@id":"https:\/\/gras-arquitectos.com\/es\/#website"},"datePublished":"2024-03-07T09:31:41+00:00","dateModified":"2025-04-23T10:30:47+00:00","description":"Pol\u00edtica de cookies, las usamos para mejorar tu experiencia, personalizar contenido y ofrecer publicidad relevante","breadcrumb":{"@id":"https:\/\/gras-arquitectos.com\/es\/politica-de-cookies\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/gras-arquitectos.com\/es\/politica-de-cookies\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/gras-arquitectos.com\/es\/politica-de-cookies\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/gras-arquitectos.com\/es\/"},{"@type":"ListItem","position":2,"name":"Pol\u00edtica de Cookies"}]},{"@type":"WebSite","@id":"https:\/\/gras-arquitectos.com\/es\/#website","url":"https:\/\/gras-arquitectos.com\/es\/","name":"GRAS Reyn\u00e9s Architecture Studio","description":"Estudio de arquitectura","publisher":{"@id":"https:\/\/gras-arquitectos.com\/es\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/gras-arquitectos.com\/es\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Organization","@id":"https:\/\/gras-arquitectos.com\/es\/#organization","name":"GRAS Reyn\u00e9s Architecture Studio","url":"https:\/\/gras-arquitectos.com\/es\/","logo":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/gras-arquitectos.com\/es\/#\/schema\/logo\/image\/","url":"https:\/\/gras-arquitectos.com\/wp-content\/uploads\/2024\/08\/0-logo-gras-arquitectos-vertical-google-1.jpg","contentUrl":"https:\/\/gras-arquitectos.com\/wp-content\/uploads\/2024\/08\/0-logo-gras-arquitectos-vertical-google-1.jpg","width":720,"height":720,"caption":"GRAS Reyn\u00e9s Architecture Studio"},"image":{"@id":"https:\/\/gras-arquitectos.com\/es\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/GRASarquitectos","https:\/\/www.instagram.com\/grasreynesarquitectos","https:\/\/www.linkedin.com\/company\/gras-reynes-arquitectos\/"]}]}},"_links":{"self":[{"href":"https:\/\/gras-arquitectos.com\/es\/wp-json\/wp\/v2\/pages\/25","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/gras-arquitectos.com\/es\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/gras-arquitectos.com\/es\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/gras-arquitectos.com\/es\/wp-json\/wp\/v2\/users\/4"}],"replies":[{"embeddable":true,"href":"https:\/\/gras-arquitectos.com\/es\/wp-json\/wp\/v2\/comments?post=25"}],"version-history":[{"count":22,"href":"https:\/\/gras-arquitectos.com\/es\/wp-json\/wp\/v2\/pages\/25\/revisions"}],"predecessor-version":[{"id":5761,"href":"https:\/\/gras-arquitectos.com\/es\/wp-json\/wp\/v2\/pages\/25\/revisions\/5761"}],"wp:attachment":[{"href":"https:\/\/gras-arquitectos.com\/es\/wp-json\/wp\/v2\/media?parent=25"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}